{"id":5624,"date":"2019-10-25T16:59:30","date_gmt":"2019-10-25T16:59:30","guid":{"rendered":"http:\/\/anklaazul.com\/?page_id=5624"},"modified":"2026-02-06T02:18:43","modified_gmt":"2026-02-06T07:18:43","slug":"contact","status":"publish","type":"page","link":"https:\/\/anklaazul.com\/es\/contact\/","title":{"rendered":"Contacto"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section section_has_divider et_pb_bottom_divider preset--module--divi-section--w88hvb799a\">\n<div class=\"et_pb_row_0 et_pb_row et_pb_gutters2 et_block_row preset--module--divi-row--xvx04f4ufr\">\n<div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_slider_0 et_pb_slider et_pb_slider_fullwidth_off et_slider_auto et_slider_speed_5000 et_pb_module et_block_module preset--module--divi-slider--2cpkexw9to\"><div class=\"et_pb_slides\">\n<div class=\"et_pb_slide_0 et_pb_slide et_pb_slider_with_overlay et_pb_media_alignment_center et_pb_bg_layout_dark et_pb_text_align_center\" data-slide-id=\"divi\/slide-0\"><div class=\"et_pb_slide_overlay_container\"><\/div><div class=\"et_pb_container\"><div class=\"et_pb_slider_container_inner\"><div class=\"et_pb_slide_description\"><h2 class=\"et_pb_slide_title\"><a href=\"https:\/\/anklaazul.com\/es\/discover-scuba-diving\/#Try-Scuba-booking\" target=\"\" class=\"et_pb_slide_title_link\">Planeemos tu buceo<\/a><\/h2><div class=\"et_pb_slide_content\"><p data-path-to-node=\"9,0\">\u00bfTienes preguntas? Estamos aqu\u00ed para ayudarte a organizar la aventura perfecta en el Pac\u00edfico.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_1 et_pb_row et_flex_row preset--module--divi-row--xvx04f4ufr\">\n<div class=\"et_pb_column_1 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_24_24_tabletWide preset--module--divi-column--nso4pnzar4\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--70382c69-3f4a-41e8-a6a7-7a62269ce8a8\"><div class=\"et_pb_text_inner\"><h1 style=\"text-align: left;\">Contacta a Ankla Azul \u2014 Comienza tu aventura<\/h1>\n<\/div><\/div>\n\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--d2da5c7d-49b3-4360-bdaa-cbd953142bee\"><div class=\"et_pb_text_inner\"><p data-path-to-node=\"15\">Ya sea que est\u00e9s listo para reservar, tengas una pregunta m\u00e9dica espec\u00edfica o simplemente quieras saber qu\u00e9 vida marina est\u00e1 en temporada, nos encantar\u00eda saber de ti. Somos un equipo peque\u00f1o y apasionado, y cuando nos contactas, hablas directamente con un buzo en Bah\u00eda Solano.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_flex_section section_has_divider et_pb_top_divider\" id=\"Scuba-Course-courses-page\"><div class=\"et_pb_top_inside_divider et-no-transition\"><\/div>\n<div class=\"et_pb_row_2 et_pb_row et_pb_equal_columns et_pb_gutters2 et_block_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_2 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--82942d87-abce-4212-b2b8-c879852860d1\"><div class=\"et_pb_text_inner\"><h2>Haz del \u00f3ceano tu historia<\/h2>\n<\/div><\/div>\n\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--d2da5c7d-49b3-4360-bdaa-cbd953142bee\"><div class=\"et_pb_text_inner\"><p data-path-to-node=\"19\"><em><b>Estamos listos para responder tus preguntas.<\/b><\/em><\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_3 et_pb_row et_flex_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_3 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_12_24_tabletWide\">\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><b>Opci\u00f3n 1: Chatear por WhatsApp (M\u00e1s r\u00e1pido)<\/b> La manera m\u00e1s r\u00e1pida de contactarnos. Perfecto para consultar disponibilidad y preguntas r\u00e1pidas.<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper preset--module--divi-button--w112ovmeye_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-button--w112ovmeye\" href=\"\" data-icon=\"\uf232\" data-interaction-trigger=\"9w3x074d6z\">Chatea en WhatsApp<\/a><\/div>\n\n<div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_clickable et_pb_module et_flex_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p><span style=\"color: #38b6ff;\">+57<\/span> 311 28 11079<\/p>\n<\/div>\n<div class=\"et_pb_icon_0 et_pb_icon et_pb_module et_flex_module\"><span class=\"et_pb_icon_wrap\"><span class=\"et-pb-icon\">\ue090<\/span><\/span><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_column_4 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_12_24_tabletWide\">\n<div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><b>Opci\u00f3n 2: Env\u00edanos un correo electr\u00f3nico<\/b> \u00bfPrefieres escribir? Env\u00edanos un correo y te responderemos en un plazo de 24 horas.<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper preset--module--divi-button--w112ovmeye_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-button--w112ovmeye\" href=\"mailto:contact@anklaazul.com\" data-icon=\"\uf0e0\" data-interaction-trigger=\"9w3x074d6z\">Email us<\/a><\/div>\n\n<div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_clickable et_pb_module et_flex_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p><span style=\"color: #38b6ff;\">Contact@anklaazul.com<\/span><\/p>\n<\/div>\n<div class=\"et_pb_icon_1 et_pb_icon et_pb_module et_flex_module\"><span class=\"et_pb_icon_wrap\"><span class=\"et-pb-icon\">\uf0e0<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_4 et_pb_row et_flex_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_5 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_12_24_tabletWide\">\n<div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p data-path-to-node=\"26\" style=\"text-align: left;\"><b>Opci\u00f3n 3: Vis\u00edtanos en la tienda<\/b> Estamos ubicados en el coraz\u00f3n de Bah\u00eda Solano (Mutis), justo al lado del mar.<\/p>\n<p data-path-to-node=\"27,0,0\" style=\"text-align: left;\"><b>Direcci\u00f3n:<\/b> Ankla Azul Diving Center, Bah\u00eda Solano (Mutis), junto al Hotel Bah\u00eda Yubarta y al Hotel Costa Choc\u00f3.<br \/><b><br \/>Horarios:<\/b><\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li data-path-to-node=\"27,1,1,0,0\" style=\"text-align: left;\"><b>Lunes - Viernes<\/b> 8:00 AM \u2013 6:00 PM<\/li>\n<li data-path-to-node=\"27,1,1,1,0\" style=\"text-align: left;\"><b>S\u00e1bado:<\/b> 8:00 AM \u2013 12:00 PM<\/li>\n<li data-path-to-node=\"27,1,1,2,0\" style=\"text-align: left;\"><b>Domingo:<\/b> <i>Solo buceo (Atenci\u00f3n al cliente cerrada)<\/i><\/li>\n<li data-path-to-node=\"27,1,1,3,0\" style=\"text-align: left;\"><i>Nota: Los Buceos de Prueba (Try Dives) comienzan a las 7:00 AM con cita previa.<\/i><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_6 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_12_24_tabletWide\">\n<div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p data-path-to-node=\"28\" style=\"text-align: left;\"><b>Opci\u00f3n 4: S\u00edguenos (Redes Sociales)<\/b> See what's happening in the Pacific right now! We post frequent updates on conditions, sightings, and promotions.<\/p>\n<\/div><\/div>\n\n<ul class=\"et_pb_social_media_follow_0 et_pb_social_media_follow et_pb_bg_layout_light et_pb_text_align_left et_pb_module et_flex_module\">\n<li class=\"et_pb_social_media_follow_network_0 et_pb_social_media_follow_network et_pb_social_icon et_pb_social_network_link et-social-instagram et_pb_module et_flex_module\"><a href=\"https:\/\/www.instagram.com\/anklaazul\/\" class=\"icon\" target=\"_self\" title=\"Follow on Instagram\" rel=\"noopener\"><span class=\"et_pb_social_media_follow_network_name\">Follow<\/span><\/a><\/li>\n\n<li class=\"et_pb_social_media_follow_network_1 et_pb_social_media_follow_network et_pb_social_icon et_pb_social_network_link et-social-facebook et_pb_module et_flex_module\"><a href=\"https:\/\/www.facebook.com\/anklaazul\" class=\"icon\" target=\"_self\" title=\"Follow on Facebook\" rel=\"noopener\"><span class=\"et_pb_social_media_follow_network_name\">Follow<\/span><\/a><\/li>\n\n<li class=\"et_pb_social_media_follow_network_2 et_pb_social_media_follow_network et_pb_social_icon et_pb_social_network_link et-pb-social-fa-icon et-social-tiktok et_pb_module et_flex_module\"><a href=\"https:\/\/www.tiktok.com\/@anklaazul\" class=\"icon\" target=\"_self\" title=\"Follow on Tiktok\" rel=\"noopener\"><span class=\"et_pb_social_media_follow_network_name\">Follow<\/span><\/a><\/li>\n\n<li class=\"et_pb_social_media_follow_network_3 et_pb_social_media_follow_network et_pb_social_icon et_pb_social_network_link et-social-youtube et_pb_module et_flex_module\"><a href=\"https:\/\/www.youtube.com\/channel\/UC-9a3gRO59HZLPXj9LmVQLw\" class=\"icon\" target=\"_self\" title=\"Follow on Youtube\" rel=\"noopener\"><span class=\"et_pb_social_media_follow_network_name\">Follow<\/span><\/a><\/li>\n\n<li class=\"et_pb_social_media_follow_network_4 et_pb_social_media_follow_network et_pb_social_icon et_pb_social_network_link et-pb-social-fa-icon et-social-whatsapp et_pb_module et_flex_module\"><a href=\"https:\/\/wa.me\/573112811079\" class=\"icon\" target=\"_self\" title=\"Follow on Whatsapp\" rel=\"noopener\"><span class=\"et_pb_social_media_follow_network_name\">Follow<\/span><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_5 et_pb_row et_flex_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_7 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_12_24_tabletWide\">\n<div class=\"et_pb_text_10 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p style=\"text-align: left;\">5. \ud83d\udccd Mapa de Ubicaci\u00f3n <b>C\u00f3mo encontrarnos:<\/b> Estamos ubicados justo frente al <b>Hotel Costa Choc\u00f3<\/b> y al lado del <b>el Hotel Bah\u00eda Yubarta<\/b>Busca la <b>tienda azul pintada con peces<\/b> and the Ankla Azul sign\u2014you can't miss us!<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_text_11 et_pb_text et_pb_bg_layout_light et_clickable et_pb_module et_flex_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3966.278604695784!2d-77.40942802232182!3d6.226950793761162!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x8e4933dede4ac487%3A0xb086ae08097319bc!2sAnkla%20Azul%20%7C%20Centro%20de%20buceo%20%7C%20Diving%20center%20%F0%9F%A4%BF%20Colombia!5e0!3m2!1sen!2sco!4v1764602978874!5m2!1sen!2sco\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe><\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_8 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_12_24_tabletWide\">\n<div class=\"et_pb_text_12 et_pb_text et_pb_bg_layout_light et_clickable et_pb_module et_flex_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p style=\"text-align: left;\">Consejos R\u00e1pidos de Viaje <b>\u00bfPlaneando tu viaje a Bah\u00eda Solano?<\/b><\/p>\n<ul data-path-to-node=\"37\">\n<li style=\"text-align: left;\">\n<p data-path-to-node=\"37,0,0\" style=\"text-align: left;\"><span class=\"citation-1\"><\/span><b><span class=\"citation-1\">Vuelos:<\/span><\/b><span class=\"citation-1\"> Puedes volar directamente desde <\/span><b><span class=\"citation-1\">Medell\u00edn (EOH)<\/span><\/b><span class=\"citation-1\"> o <\/span><b><span class=\"citation-1\">Quibd\u00f3 (UIB)<\/span><\/b><span class=\"citation-1 citation-end-1\"> hacia Bah\u00eda Solano (BSC).<source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c1002869892=\"\"><sup _ngcontent-ng-c1002869892=\"\" class=\"superscript\" data-turn-source-index=\"1\"><\/sup><\/source-footnote><\/span><sources-carousel-inline ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c1782509658=\"\"><source-inline-chips _ngcontent-ng-c1782509658=\"\" _nghost-ng-c2631690858=\"\" class=\"ng-star-inserted\"><source-inline-chip _ngcontent-ng-c2631690858=\"\" _nghost-ng-c1832570132=\"\" class=\"ng-star-inserted\"><\/source-inline-chip><\/source-inline-chips><\/sources-carousel-inline><\/p>\n<\/li>\n<li style=\"text-align: left;\">\n<p data-path-to-node=\"37,1,0\"><b>Aerol\u00edneas:<\/b> Satena, Clic (EasyFly) o Moon Flights.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"37,2,0\" style=\"text-align: left;\"><b>Llegada:<\/b> \u00a1Podemos organizar tu recogida en el aeropuerto si nos compartes los detalles de tu vuelo con anticipaci\u00f3n!<\/p>\n<\/li>\n<\/ul>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_2_wrapper preset--module--divi-button--p90tt5zbku_wrapper\"><a class=\"et_pb_button_2 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--p90tt5zbku\" href=\"https:\/\/anklaazul.com\/es\/coming-soon\/\" data-icon=\"9\" data-interaction-trigger=\"xqecjy1t3k\">Ver la Gu\u00eda de Viaje Completa<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_2 et_pb_section et_section_regular et_flex_section\"><div class=\"et_pb_row_6 et_pb_row et_flex_row preset--module--divi-row--default\"><div class=\"et_pb_column_9 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_24_24_tabletWide\"><div class=\"et_pb_text_13 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--efokf8vg5e\"><div class=\"et_pb_text_inner\"><h2 style=\"text-align: center\">Lo que dicen los Buzos<\/h2>\n<\/div><\/div><div class=\"et_pb_text_14 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png\" width=\"100\" height=\"26\" alt=\"\" class=\"wp-image-29150 aligncenter size-full\" \/>400+ Reviews<\/p>\n<\/div><\/div><div class=\"et_pb_group_0 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_0 et_pb_image et_pb_module et_block_module preset--module--divi-image--default\"><a href=\"https:\/\/share.google\/EAU6MO52XxyqvOP0h\" target=\"_blank\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/1.png\" alt=\"Google Reviews\" title=\"Read our Google Reviews\" width=\"250\" height=\"250\" srcset=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/1.png 250w, https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/1-150x150.png 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" class=\"wp-image-29151\" \/><\/span><\/a><\/div><div class=\"et_pb_image_1 et_pb_image et_pb_module et_block_module preset--module--divi-image--default\"><a href=\"https:\/\/www.tripadvisor.com\/Attraction_Review-g1983809-d17747988-Reviews-Ankla_Azul-Bahia_Solano_Choco_Department.html\" target=\"_blank\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/2.png\" alt=\"TripAdvisor Reviews\" title=\"Ankla Azul on TripAdvisor\" width=\"250\" height=\"250\" srcset=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/2.png 250w, https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/2-150x150.png 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" class=\"wp-image-29152\" \/><\/span><\/a><\/div><\/div><\/div><\/div><div class=\"et_pb_row_7 et_pb_row et_flex_row preset--module--divi-row--default\"><div class=\"et_pb_column_10 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_8_24_tabletWide\"><div class=\"et_pb_text_15 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--59427334-4174-403d-867b-228210bb891c\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\">Vinha Damanta<\/h3>\n<\/div><\/div><div class=\"et_pb_image_2 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png\" alt=\"5 starts\" title=\"5 starts\" width=\"270\" height=\"70\" srcset=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png 270w\" sizes=\"(max-width: 270px) 100vw, 270px\" class=\"wp-image-29150\" \/><\/span><\/div><div class=\"et_pb_text_16 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p style=\"text-align: justify;\">Hice 3 inmersiones con el equipo de Ankla Azul y las tres fueron geniales\u2026 El centro de buceo presta mucha atenci\u00f3n a la seguridad y a seguir los procedimientos correctos, lo que te da una gran sensaci\u00f3n de seguridad. Tienen un equipo excelente, casi nuevo, y te equipan como a un profesional.<\/p>\n<\/div><\/div><\/div><div class=\"et_pb_column_11 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_8_24_tabletWide\"><div class=\"et_pb_text_17 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--59427334-4174-403d-867b-228210bb891c\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\">Magda K<\/h3>\n<\/div><\/div><div class=\"et_pb_image_3 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png\" alt=\"5 starts\" title=\"5 starts\" width=\"270\" height=\"70\" srcset=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png 270w\" sizes=\"(max-width: 270px) 100vw, 270px\" class=\"wp-image-29150\" \/><\/span><\/div><div class=\"et_pb_text_18 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p style=\"text-align: justify;\">El centro de buceo nos impresion\u00f3 much\u00edsimo: el equipo era de alt\u00edsima calidad, lo que hizo que cada inmersi\u00f3n fuera c\u00f3moda y segura\u2026 Adem\u00e1s del buceo con tanque, tuvimos la oportunidad de probar el freediving, que en la cascada fue una experiencia absolutamente \u00fanica.<\/p>\n<\/div><\/div><\/div><div class=\"et_pb_column_12 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_8_24_tabletWide\"><div class=\"et_pb_text_19 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--59427334-4174-403d-867b-228210bb891c\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\">Nicole Reynolds<\/h3>\n<\/div><\/div><div class=\"et_pb_image_4 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png\" alt=\"5 starts\" title=\"5 starts\" width=\"270\" height=\"70\" srcset=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png 270w\" sizes=\"(max-width: 270px) 100vw, 270px\" class=\"wp-image-29150\" \/><\/span><\/div><div class=\"et_pb_text_20 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p style=\"text-align: justify;\">Pas\u00e9 tres d\u00edas con el equipo de Ankla Azul haciendo buceo y fue una experiencia incre\u00edble\u2026 Ja, el dive master principal e instructor, se enorgullece de sus excursiones de buceo y es evidente el enorme amor que siente por Bah\u00eda Solano y la vida silvestre de este lugar.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_8 et_pb_row et_flex_row preset--module--divi-row--default\"><div class=\"et_pb_column_13 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_8_24_tabletWide\"><div class=\"et_pb_text_21 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--59427334-4174-403d-867b-228210bb891c\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\">Gloria Guillin Cuello<\/h3>\n<\/div><\/div><div class=\"et_pb_image_5 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png\" alt=\"5 starts\" title=\"5 starts\" width=\"270\" height=\"70\" srcset=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png 270w\" sizes=\"(max-width: 270px) 100vw, 270px\" class=\"wp-image-29150\" \/><\/span><\/div><div class=\"et_pb_text_22 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p style=\"text-align: justify;\"><span class=\"citation-174 citation-end-174\">Esta vez hice mi primera inmersi\u00f3n con Ankla Azul y otros tres amigos. La experiencia fue espectacular, desde el inicio de la capacitaci\u00f3n hasta la sesi\u00f3n pr\u00e1ctica. Nuestro instructor demostr\u00f3 amabilidad y conocimiento, brind\u00e1ndonos una gu\u00eda segura.<sup class=\"superscript\" data-turn-source-index=\"2\"><\/sup><\/span>e.\"<\/p>\n<\/div><\/div><\/div><div class=\"et_pb_column_14 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_8_24_tabletWide\"><div class=\"et_pb_text_23 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--59427334-4174-403d-867b-228210bb891c\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\">Ad\u00e8le B<\/h3>\n<\/div><\/div><div class=\"et_pb_image_6 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png\" alt=\"5 starts\" title=\"5 starts\" width=\"270\" height=\"70\" srcset=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png 270w\" sizes=\"(max-width: 270px) 100vw, 270px\" class=\"wp-image-29150\" \/><\/span><\/div><div class=\"et_pb_text_24 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p style=\"text-align: justify;\">\u00a1Una experiencia absolutamente incre\u00edble! La inmersi\u00f3n fue inolvidable; pudimos escuchar a las ballenas cantar bajo el agua todo el tiempo\u2026 El equipo de Ankla Azul es s\u00faper profesional, el equipo es de primera calidad y todo se sinti\u00f3 muy seguro y bien organizado.<\/p>\n<\/div><\/div><\/div><div class=\"et_pb_column_15 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_8_24_tabletWide\"><div class=\"et_pb_text_25 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--59427334-4174-403d-867b-228210bb891c\"><div class=\"et_pb_text_inner\"><h3>Dayana Jamaica<\/h3>\n<\/div><\/div><div class=\"et_pb_image_7 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png\" alt=\"5 starts\" title=\"5 starts\" width=\"270\" height=\"70\" srcset=\"https:\/\/anklaazul.com\/wp-content\/uploads\/2023\/07\/Untitled-design-7.png 270w\" sizes=\"(max-width: 270px) 100vw, 270px\" class=\"wp-image-29150\" \/><\/span><\/div><div class=\"et_pb_text_26 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p style=\"text-align: justify;\"><span>Excellent experience. Andr\u00e9s and V\u00edctor are amazing\u2014very kind, attentive, and careful. They made us feel safe at all times and helped us truly enjoy the dive, even though we had no prior experience. We had a great time, 100% recommended.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_section_3 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_9 et_pb_row et_flex_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_16 et_pb_column et-last-child et_grid_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_24_24_tabletWide\">\n<div class=\"et_pb_text_27 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--efokf8vg5e\"><div class=\"et_pb_text_inner\"><h2>Mucho m\u00e1s que solo mover las aletas<\/h2>\n<\/div><\/div>\n\n<div class=\"et_pb_text_28 et_pb_text et_pb_bg_layout_dark et_pb_module et_block_module preset--module--divi-text--3tx68shv89\"><div class=\"et_pb_text_inner\"><p style=\"text-align: justify\">En Ankla Azul, el buceo es mucho m\u00e1s que mover las aletas. Es ense\u00f1anza paciente, seguridad rigurosa y un cuidado genuino por el lugar que llamamos hogar. Como Centro de Formaci\u00f3n de Instructores SSI y Centro SSI Blue Oceans (reconocimiento 2025), combinamos el desarrollo de habilidades con la conciencia oce\u00e1nica\u2014identificaci\u00f3n de peces, trabajo en viveros de coral, educaci\u00f3n comunitaria y apoyo en rescate\u2014para que cada inmersi\u00f3n fortalezca la confianza y el respeto por el Pac\u00edfico salvaje de Bah\u00eda Solano.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":378422,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5624","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/anklaazul.com\/es\/wp-json\/wp\/v2\/pages\/5624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anklaazul.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anklaazul.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anklaazul.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anklaazul.com\/es\/wp-json\/wp\/v2\/comments?post=5624"}],"version-history":[{"count":0,"href":"https:\/\/anklaazul.com\/es\/wp-json\/wp\/v2\/pages\/5624\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anklaazul.com\/es\/wp-json\/wp\/v2\/media\/378422"}],"wp:attachment":[{"href":"https:\/\/anklaazul.com\/es\/wp-json\/wp\/v2\/media?parent=5624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}